{"id":4578,"date":"2023-05-10T18:36:19","date_gmt":"2023-05-10T16:36:19","guid":{"rendered":"https:\/\/chorverband-region-kocher.de\/cms\/?post_type=tribe_events&#038;p=4578"},"modified":"2023-06-21T23:10:59","modified_gmt":"2023-06-21T21:10:59","slug":"regionalkonzert-125-jahre-cvrk","status":"publish","type":"tribe_events","link":"https:\/\/chorverband-region-kocher.de\/cms\/termin\/regionalkonzert-125-jahre-cvrk\/","title":{"rendered":"Regionalkonzert 125 Jahre CVRK des Gesangverein Liederkranz Hollenbach"},"content":{"rendered":"<p>Im Rahmen des 125-j\u00e4hrigen bestehens des Chorverbands Region Kocher gibt der Liederkranz Hollenbach ein Regionalkonzert mit 6-7 Ch\u00f6ren in der Dreschhalle Hollenbach<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Rahmen des 125-j\u00e4hrigen bestehens des Chorverbands Region Kocher gibt der Liederkranz Hollenbach ein Regionalkonzert mit 6-7 Ch\u00f6ren in der Dreschhalle Hollenbach &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4578","tribe_events","type-tribe_events","status-publish","hentry","no-thumb"],"_links":{"self":[{"href":"https:\/\/chorverband-region-kocher.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chorverband-region-kocher.de\/cms\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/chorverband-region-kocher.de\/cms\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/chorverband-region-kocher.de\/cms\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":3,"href":"https:\/\/chorverband-region-kocher.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4578\/revisions"}],"predecessor-version":[{"id":5072,"href":"https:\/\/chorverband-region-kocher.de\/cms\/wp-json\/wp\/v2\/tribe_events\/4578\/revisions\/5072"}],"wp:attachment":[{"href":"https:\/\/chorverband-region-kocher.de\/cms\/wp-json\/wp\/v2\/media?parent=4578"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chorverband-region-kocher.de\/cms\/wp-json\/wp\/v2\/tags?post=4578"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/chorverband-region-kocher.de\/cms\/wp-json\/wp\/v2\/tribe_events_cat?post=4578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}